{"id":40122,"count":1,"description":"","link":"https:\/\/www.infoescuelas.com\/eeuu\/new-hampshire\/north-hampton\/","name":"North Hampton","slug":"north-hampton","taxonomy":"category","parent":39899,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Escuelas y colegios de North Hampton. Informaci\u00f3n y opiniones.<\/title>\n<meta name=\"description\" content=\"Escuelas y colegios de North Hampton. Encuentra informaci\u00f3n y los mejores colegios de North Hampton. Opiniones de padres, alumnos y profesores y otros centros educativos y escuelas de North Hampton.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Escuelas y colegios de North Hampton. Informaci\u00f3n y opiniones.\" \/>\n<meta property=\"og:description\" content=\"Escuelas y colegios de North Hampton. Encuentra informaci\u00f3n y los mejores colegios de North Hampton. Opiniones de padres, alumnos y profesores y otros centros educativos y escuelas de North Hampton.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.infoescuelas.com\/eeuu\/new-hampshire\/north-hampton\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuelas de EEUU - Informaci\u00f3n y opiniones\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.infoescuelas.com\/eeuu\/new-hampshire\/north-hampton\/\",\"url\":\"https:\/\/www.infoescuelas.com\/eeuu\/new-hampshire\/north-hampton\/\",\"name\":\"Escuelas y colegios de North Hampton. Informaci\u00f3n y opiniones.\",\"isPartOf\":{\"@id\":\"https:\/\/www.infoescuelas.com\/eeuu\/#website\"},\"description\":\"Escuelas y colegios de North Hampton. Encuentra informaci\u00f3n y los mejores colegios de North Hampton. Opiniones de padres, alumnos y profesores y otros centros educativos y escuelas de North Hampton.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.infoescuelas.com\/eeuu\/new-hampshire\/north-hampton\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.infoescuelas.com\/eeuu\/new-hampshire\/north-hampton\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Escuelas de EEUU\",\"item\":\"https:\/\/www.infoescuelas.com\/eeuu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NEW HAMPSHIRE\",\"item\":\"https:\/\/www.infoescuelas.com\/eeuu\/new-hampshire\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"North Hampton\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.infoescuelas.com\/eeuu\/#website\",\"url\":\"https:\/\/www.infoescuelas.com\/eeuu\/\",\"name\":\"Escuelas de EEUU - Informaci\u00f3n y opiniones\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.infoescuelas.com\/eeuu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.infoescuelas.com\/eeuu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.infoescuelas.com\/eeuu\/#organization\",\"name\":\"Escuelas de EEUU - Informaci\u00f3n y opiniones\",\"url\":\"https:\/\/www.infoescuelas.com\/eeuu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.infoescuelas.com\/eeuu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.infoescuelas.com\/eeuu\/wp-content\/uploads\/2021\/10\/cropped-logo-infoescuelas-1.png\",\"contentUrl\":\"https:\/\/www.infoescuelas.com\/eeuu\/wp-content\/uploads\/2021\/10\/cropped-logo-infoescuelas-1.png\",\"width\":359,\"height\":83,\"caption\":\"Escuelas de EEUU - Informaci\u00f3n y opiniones\"},\"image\":{\"@id\":\"https:\/\/www.infoescuelas.com\/eeuu\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Escuelas y colegios de North Hampton. Informaci\u00f3n y opiniones.","description":"Escuelas y colegios de North Hampton. Encuentra informaci\u00f3n y los mejores colegios de North Hampton. Opiniones de padres, alumnos y profesores y otros centros educativos y escuelas de North Hampton.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Escuelas y colegios de North Hampton. Informaci\u00f3n y opiniones.","og_description":"Escuelas y colegios de North Hampton. Encuentra informaci\u00f3n y los mejores colegios de North Hampton. Opiniones de padres, alumnos y profesores y otros centros educativos y escuelas de North Hampton.","og_url":"https:\/\/www.infoescuelas.com\/eeuu\/new-hampshire\/north-hampton\/","og_site_name":"Escuelas de EEUU - Informaci\u00f3n y opiniones","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.infoescuelas.com\/eeuu\/new-hampshire\/north-hampton\/","url":"https:\/\/www.infoescuelas.com\/eeuu\/new-hampshire\/north-hampton\/","name":"Escuelas y colegios de North Hampton. Informaci\u00f3n y opiniones.","isPartOf":{"@id":"https:\/\/www.infoescuelas.com\/eeuu\/#website"},"description":"Escuelas y colegios de North Hampton. Encuentra informaci\u00f3n y los mejores colegios de North Hampton. Opiniones de padres, alumnos y profesores y otros centros educativos y escuelas de North Hampton.","breadcrumb":{"@id":"https:\/\/www.infoescuelas.com\/eeuu\/new-hampshire\/north-hampton\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.infoescuelas.com\/eeuu\/new-hampshire\/north-hampton\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Escuelas de EEUU","item":"https:\/\/www.infoescuelas.com\/eeuu\/"},{"@type":"ListItem","position":2,"name":"NEW HAMPSHIRE","item":"https:\/\/www.infoescuelas.com\/eeuu\/new-hampshire\/"},{"@type":"ListItem","position":3,"name":"North Hampton"}]},{"@type":"WebSite","@id":"https:\/\/www.infoescuelas.com\/eeuu\/#website","url":"https:\/\/www.infoescuelas.com\/eeuu\/","name":"Escuelas de EEUU - Informaci\u00f3n y opiniones","description":"","publisher":{"@id":"https:\/\/www.infoescuelas.com\/eeuu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.infoescuelas.com\/eeuu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.infoescuelas.com\/eeuu\/#organization","name":"Escuelas de EEUU - Informaci\u00f3n y opiniones","url":"https:\/\/www.infoescuelas.com\/eeuu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.infoescuelas.com\/eeuu\/#\/schema\/logo\/image\/","url":"https:\/\/www.infoescuelas.com\/eeuu\/wp-content\/uploads\/2021\/10\/cropped-logo-infoescuelas-1.png","contentUrl":"https:\/\/www.infoescuelas.com\/eeuu\/wp-content\/uploads\/2021\/10\/cropped-logo-infoescuelas-1.png","width":359,"height":83,"caption":"Escuelas de EEUU - Informaci\u00f3n y opiniones"},"image":{"@id":"https:\/\/www.infoescuelas.com\/eeuu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.infoescuelas.com\/eeuu\/wp-json\/wp\/v2\/categories\/40122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infoescuelas.com\/eeuu\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.infoescuelas.com\/eeuu\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.infoescuelas.com\/eeuu\/wp-json\/wp\/v2\/categories\/39899"}],"wp:post_type":[{"href":"https:\/\/www.infoescuelas.com\/eeuu\/wp-json\/wp\/v2\/posts?categories=40122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}