{"id":41775,"date":"2024-05-08T20:39:49","date_gmt":"2024-05-08T18:39:49","guid":{"rendered":"https:\/\/www.infoescuelas.com\/espana2\/sin-categoria\/ies-ordes-de-ordes\/"},"modified":"2024-05-08T20:39:49","modified_gmt":"2024-05-08T18:39:49","slug":"ies-ordes-de-ordes","status":"publish","type":"post","link":"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/","title":{"rendered":"IES Ordes de Ordes"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[4085,4438],"tags":[4091],"class_list":["post-41775","post","type-post","status-publish","format-standard","hentry","category-a-coruna","category-ordes","tag-instituto-de-educacion-secundaria-ies-de-a-coruna"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>IES Ordes de Ordes - Infoescuelas Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IES Ordes de Ordes - Infoescuelas Espa\u00f1a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/\" \/>\n<meta property=\"og:site_name\" content=\"Infoescuelas Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-08T18:39:49+00:00\" \/>\n<meta name=\"author\" content=\"profe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"profe\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/\"},\"author\":{\"name\":\"profe\",\"@id\":\"https:\/\/www.infoescuelas.com\/espana\/#\/schema\/person\/8ac2d368e293d4724257e8aac07e76ef\"},\"headline\":\"IES Ordes de Ordes\",\"datePublished\":\"2024-05-08T18:39:49+00:00\",\"dateModified\":\"2024-05-08T18:39:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/\"},\"wordCount\":4,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.infoescuelas.com\/espana\/#organization\"},\"keywords\":[\"Instituto de Educaci\u00f3n Secundaria (IES) de A Coru\u00f1a\"],\"articleSection\":[\"A Coru\u00f1a\",\"Ordes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/\",\"url\":\"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/\",\"name\":\"IES Ordes de Ordes - Infoescuelas Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\/\/www.infoescuelas.com\/espana\/#website\"},\"datePublished\":\"2024-05-08T18:39:49+00:00\",\"dateModified\":\"2024-05-08T18:39:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.infoescuelas.com\/espana\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IES Ordes de Ordes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.infoescuelas.com\/espana\/#website\",\"url\":\"https:\/\/www.infoescuelas.com\/espana\/\",\"name\":\"Infoescuelas Espa\u00f1a\",\"description\":\"Informaci\u00f3n de colegios y dem\u00e1s centros educativos de Espa\u00f1a\",\"publisher\":{\"@id\":\"https:\/\/www.infoescuelas.com\/espana\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.infoescuelas.com\/espana\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.infoescuelas.com\/espana\/#organization\",\"name\":\"Infoescuelas Espa\u00f1a\",\"url\":\"https:\/\/www.infoescuelas.com\/espana\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.infoescuelas.com\/espana\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.infoescuelas.com\/espana\/wp-content\/uploads\/2024\/12\/logo.png\",\"contentUrl\":\"https:\/\/www.infoescuelas.com\/espana\/wp-content\/uploads\/2024\/12\/logo.png\",\"width\":181,\"height\":181,\"caption\":\"Infoescuelas Espa\u00f1a\"},\"image\":{\"@id\":\"https:\/\/www.infoescuelas.com\/espana\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.infoescuelas.com\/espana\/#\/schema\/person\/8ac2d368e293d4724257e8aac07e76ef\",\"name\":\"profe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.infoescuelas.com\/espana\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/56177ebc2a7b745e198d23790c44b499df782a52f13ff8f916d774c438cf8708?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/56177ebc2a7b745e198d23790c44b499df782a52f13ff8f916d774c438cf8708?s=96&d=mm&r=g\",\"caption\":\"profe\"},\"sameAs\":[\"https:\/\/www.infoescuelas.com\/espana2\"],\"url\":\"https:\/\/www.infoescuelas.com\/espana\/author\/profe\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IES Ordes de Ordes - Infoescuelas Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/","og_locale":"es_ES","og_type":"article","og_title":"IES Ordes de Ordes - Infoescuelas Espa\u00f1a","og_url":"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/","og_site_name":"Infoescuelas Espa\u00f1a","article_published_time":"2024-05-08T18:39:49+00:00","author":"profe","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"profe"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/#article","isPartOf":{"@id":"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/"},"author":{"name":"profe","@id":"https:\/\/www.infoescuelas.com\/espana\/#\/schema\/person\/8ac2d368e293d4724257e8aac07e76ef"},"headline":"IES Ordes de Ordes","datePublished":"2024-05-08T18:39:49+00:00","dateModified":"2024-05-08T18:39:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/"},"wordCount":4,"commentCount":0,"publisher":{"@id":"https:\/\/www.infoescuelas.com\/espana\/#organization"},"keywords":["Instituto de Educaci\u00f3n Secundaria (IES) de A Coru\u00f1a"],"articleSection":["A Coru\u00f1a","Ordes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/","url":"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/","name":"IES Ordes de Ordes - Infoescuelas Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.infoescuelas.com\/espana\/#website"},"datePublished":"2024-05-08T18:39:49+00:00","dateModified":"2024-05-08T18:39:49+00:00","breadcrumb":{"@id":"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.infoescuelas.com\/espana\/a-coruna\/ies-ordes-de-ordes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.infoescuelas.com\/espana\/"},{"@type":"ListItem","position":2,"name":"IES Ordes de Ordes"}]},{"@type":"WebSite","@id":"https:\/\/www.infoescuelas.com\/espana\/#website","url":"https:\/\/www.infoescuelas.com\/espana\/","name":"Infoescuelas Espa\u00f1a","description":"Informaci\u00f3n de colegios y dem\u00e1s centros educativos de Espa\u00f1a","publisher":{"@id":"https:\/\/www.infoescuelas.com\/espana\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.infoescuelas.com\/espana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.infoescuelas.com\/espana\/#organization","name":"Infoescuelas Espa\u00f1a","url":"https:\/\/www.infoescuelas.com\/espana\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.infoescuelas.com\/espana\/#\/schema\/logo\/image\/","url":"https:\/\/www.infoescuelas.com\/espana\/wp-content\/uploads\/2024\/12\/logo.png","contentUrl":"https:\/\/www.infoescuelas.com\/espana\/wp-content\/uploads\/2024\/12\/logo.png","width":181,"height":181,"caption":"Infoescuelas Espa\u00f1a"},"image":{"@id":"https:\/\/www.infoescuelas.com\/espana\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.infoescuelas.com\/espana\/#\/schema\/person\/8ac2d368e293d4724257e8aac07e76ef","name":"profe","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.infoescuelas.com\/espana\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/56177ebc2a7b745e198d23790c44b499df782a52f13ff8f916d774c438cf8708?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56177ebc2a7b745e198d23790c44b499df782a52f13ff8f916d774c438cf8708?s=96&d=mm&r=g","caption":"profe"},"sameAs":["https:\/\/www.infoescuelas.com\/espana2"],"url":"https:\/\/www.infoescuelas.com\/espana\/author\/profe\/"}]}},"_links":{"self":[{"href":"https:\/\/www.infoescuelas.com\/espana\/wp-json\/wp\/v2\/posts\/41775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infoescuelas.com\/espana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.infoescuelas.com\/espana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.infoescuelas.com\/espana\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infoescuelas.com\/espana\/wp-json\/wp\/v2\/comments?post=41775"}],"version-history":[{"count":0,"href":"https:\/\/www.infoescuelas.com\/espana\/wp-json\/wp\/v2\/posts\/41775\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.infoescuelas.com\/espana\/wp-json\/wp\/v2\/media?parent=41775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.infoescuelas.com\/espana\/wp-json\/wp\/v2\/categories?post=41775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.infoescuelas.com\/espana\/wp-json\/wp\/v2\/tags?post=41775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}